{"id":19,"count":4,"description":"","link":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/","name":"Books","slug":"books","taxonomy":"category","parent":14,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Books Archives - Metal Type<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Books Archives - Metal Type\" \/>\n<meta property=\"og:url\" content=\"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/\" \/>\n<meta property=\"og:site_name\" content=\"Metal Type\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MTPrinting\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/category\\\/trade-category\\\/books\\\/\",\"url\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/category\\\/trade-category\\\/books\\\/\",\"name\":\"Books Archives - Metal Type\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/category\\\/trade-category\\\/books\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/category\\\/trade-category\\\/books\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trade Category\",\"item\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/category\\\/trade-category\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Books\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/#website\",\"url\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/\",\"name\":\"Metal Type\",\"description\":\"Yesterday\u2019s Technology . . . Today!\",\"publisher\":{\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/#\\\/schema\\\/person\\\/a2940bf4b69879abf80bffc807423c9c\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/metaltype.co.uk\\\/wpress\\\/#\\\/schema\\\/person\\\/a2940bf4b69879abf80bffc807423c9c\",\"name\":\"Dave Hughes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r\",\"caption\":\"Dave Hughes\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r\"},\"description\":\"Ex-letterpress printer and founder of the Metal Type website.\",\"sameAs\":[\"http:\\\/\\\/metaltype.co.uk\\\/wpress\",\"https:\\\/\\\/x.com\\\/MTPrinting\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Books Archives - Metal Type","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/","og_locale":"en_US","og_type":"article","og_title":"Books Archives - Metal Type","og_url":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/","og_site_name":"Metal Type","twitter_card":"summary_large_image","twitter_site":"@MTPrinting","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/","url":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/","name":"Books Archives - Metal Type","isPartOf":{"@id":"https:\/\/metaltype.co.uk\/wpress\/#website"},"breadcrumb":{"@id":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/books\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/metaltype.co.uk\/wpress\/"},{"@type":"ListItem","position":2,"name":"Trade Category","item":"https:\/\/metaltype.co.uk\/wpress\/category\/trade-category\/"},{"@type":"ListItem","position":3,"name":"Books"}]},{"@type":"WebSite","@id":"https:\/\/metaltype.co.uk\/wpress\/#website","url":"https:\/\/metaltype.co.uk\/wpress\/","name":"Metal Type","description":"Yesterday\u2019s Technology . . . Today!","publisher":{"@id":"https:\/\/metaltype.co.uk\/wpress\/#\/schema\/person\/a2940bf4b69879abf80bffc807423c9c"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/metaltype.co.uk\/wpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/metaltype.co.uk\/wpress\/#\/schema\/person\/a2940bf4b69879abf80bffc807423c9c","name":"Dave Hughes","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r","url":"https:\/\/secure.gravatar.com\/avatar\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r","caption":"Dave Hughes"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/0782f4b557dca1d0780ba5d81bf1f2fbd00f957d5c97e2603a3ea0dd578da9a2?s=96&d=mm&r=r"},"description":"Ex-letterpress printer and founder of the Metal Type website.","sameAs":["http:\/\/metaltype.co.uk\/wpress","https:\/\/x.com\/MTPrinting"]}]}},"_links":{"self":[{"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/categories\/19","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/categories\/14"}],"wp:post_type":[{"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/posts?categories=19"},{"href":"https:\/\/metaltype.co.uk\/wpress\/wp-json\/wp\/v2\/pages?categories=19"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}